{"id":27500,"date":"2021-12-10T12:49:57","date_gmt":"2021-12-10T20:49:57","guid":{"rendered":"https:\/\/greatdemo.com\/?p=27500"},"modified":"2023-01-26T15:30:56","modified_gmt":"2023-01-26T15:30:56","slug":"evaluacion-del-nivel-de-habilidad-demostrativa-como-califica-su-equipo","status":"publish","type":"post","link":"https:\/\/greatdemo.com\/es\/assessing-demonstration-skill-levels-how-does-your-team-rate\/","title":{"rendered":"Evaluaci\u00f3n de los niveles de destreza en las demostraciones: \u00bfcu\u00e1l es la puntuaci\u00f3n de su equipo?"},"content":{"rendered":"<p class=\"p3\">Muchos profesionales de preventa y ventas afirman que son expertos en demostraciones, pero \u00bflo son?  Las organizaciones que alcanzan el nivel 12 obtienen resultados notables de escalado y amplificaci\u00f3n y establecen ventajas competitivas sustanciales frente a sus hom\u00f3logas.<\/p>\n<p class=\"p3\">He aqu\u00ed un m\u00e9todo sencillo para evaluar su situaci\u00f3n y la de su equipo, basado en doce niveles de competencia creciente: los Doce Niveles de Habilidades de Demostraci\u00f3n:<\/p>\n<p class=\"p3\">Nivel 1:<span class=\"Apple-converted-space\">\u00a0 <\/span>Sigue el gui\u00f3n de demostraci\u00f3n \"est\u00e1ndar\".<\/p>\n<p class=\"p3\">Nivel 2:<span class=\"Apple-converted-space\">\u00a0 <\/span>Personaliza en funci\u00f3n del mercado\/industria del cliente potencial.<\/p>\n<p class=\"p3\">Nivel 3:<span class=\"Apple-converted-space\">\u00a0 <\/span>Personaliza en funci\u00f3n de la informaci\u00f3n descubierta.<\/p>\n<p class=\"p3\">Nivel 4: Comunica el valor empresarial.<\/p>\n<p class=\"p3\">Nivel 5:<span class=\"Apple-converted-space\">\u00a0 <\/span>Gestiona y explora las cuestiones relativas a los prospectos.<\/p>\n<p class=\"p3\">Nivel 6: Comunica al producto las solicitudes de mejoras y nuevas funciones.<\/p>\n<p class=\"p3\">Nivel 7:<span class=\"Apple-converted-space\">\u00a0 <\/span>Utiliza preguntas tendenciosas para superar a la competencia y redise\u00f1ar la visi\u00f3n.<\/p>\n<p class=\"p3\">Nivel 8: Aplica t\u00e9cnicas narrativas para reforzar las ideas clave.<\/p>\n<p class=\"p3\">Nivel 9: Diferencia la Generaci\u00f3n de Visiones de los escenarios de Pruebas T\u00e9cnicas.<\/p>\n<p class=\"p3\">Nivel 10: Captura y reutiliza los casos de \u00e9xito de las demostraciones.<\/p>\n<p class=\"p3\">Nivel 11: Aplica estas habilidades a la amplia gama de escenarios de demostraci\u00f3n requeridos, incluyendo demostraciones para clientes potenciales que ocupan diferentes porciones de la Curva de Adopci\u00f3n Tecnol\u00f3gica, presentaci\u00f3n de nuevos productos, Centros de Informaci\u00f3n Ejecutiva, ciclos de ventas transaccionales, oportunidades de expansi\u00f3n, sesiones de almuerzo y aprendizaje, ferias comerciales, demostraciones para analistas y terceros, socios de canal, demostraciones internas y otros escenarios.<\/p>\n<p class=\"p3\">Nivel 12: Integra, alinea y aprovecha las habilidades anteriores en una metodolog\u00eda de demostraci\u00f3n cohesionada.<\/p>\n<p class=\"p3\">\u00bfD\u00f3nde se encuentran usted y su equipo en este espectro?<span class=\"Apple-converted-space\">\u00a0 <\/span>Exploremos cada nivel...<\/p>\n<p class=\"p3\"><b>Nivel 1 - Sigue el gui\u00f3n de demostraci\u00f3n \"est\u00e1ndar\".<\/b><\/p>\n<p class=\"p3\">La mayor\u00eda de los nuevos empleados de preventa y ventas reciben una formaci\u00f3n b\u00e1sica sobre los productos y sistemas de la empresa, junto con una introducci\u00f3n a las distintas fases del proceso de comercializaci\u00f3n y ventas.<span class=\"Apple-converted-space\">\u00a0 <\/span>Para los preventas y algunos vendedores, esto incluye aprender la demostraci\u00f3n b\u00e1sica de cada producto que van a representar.<\/p>\n<p class=\"p3\">Y muchas organizaciones comprueban si el nuevo miembro del equipo domina la demostraci\u00f3n \"est\u00e1ndar\" mediante un juego de rol de certificaci\u00f3n.<span class=\"Apple-converted-space\">\u00a0 <\/span>Ese es el Nivel 1, que suele centrarse en garantizar que el empleado comprenda las distintas capacidades de su software y el posicionamiento pertinente.<\/p>\n<p class=\"p3\">Tenga en cuenta que estas demostraciones \"est\u00e1ndar\" suelen estar estructuradas en forma de recorridos por el puerto asombrosamente horribles; no est\u00e1n optimizadas para ning\u00fan prospecto o escenario de demostraci\u00f3n espec\u00edfico.<span class=\"Apple-converted-space\">\u00a0 <\/span>Se espera (\u00a1ojal\u00e1!) que los profesionales de ventas y preventa s\u00f3lo utilicen estas demostraciones \"est\u00e1ndar\" como punto de partida.<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00a1Lamentable y desgraciadamente, muchas personas contin\u00faan siguiendo estos mismos caminos de demostraci\u00f3n durante a\u00f1os...!<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el Nivel 1:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">\"Certificaci\u00f3n\" por parte de un directivo, un equipo de certificaci\u00f3n, un mentor o un colega.<\/li>\n<\/ul>\n<p class=\"p3\"><b>Nivel 2 - Personalizaci\u00f3n en funci\u00f3n del mercado\/industria del cliente potencial<\/b><\/p>\n<p class=\"p3\">El primer peque\u00f1o paso hacia la personalizaci\u00f3n de las demostraciones para satisfacer las situaciones de los clientes potenciales suele reflejarse en el uso de conjuntos de datos espec\u00edficos del mercado o del sector.<span class=\"Apple-converted-space\">\u00a0 <\/span>Esto puede ser tan sencillo como utilizar un <a href=\"https:\/\/greatdemo.com\/es\/a-perfect-demo-environment\/\"><span class=\"s2\">entorno de demostraci\u00f3n<\/span><\/a> para cada industria: manufacturera, financiera, farmac\u00e9utica, etc. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">A falta de entornos preconfigurados, los profesionales podr\u00edan modificar los datos ellos mismos y\/o aplicar la terminolog\u00eda adecuada sobre la marcha en su exposici\u00f3n verbal durante la demostraci\u00f3n.<\/p>\n<p class=\"p3\">Otra dimensi\u00f3n de este nivel de personalizaci\u00f3n es la adaptaci\u00f3n de la demo a las especificidades de una regi\u00f3n, que puede ir desde la inclusi\u00f3n de direcciones regionales o sintaxis telef\u00f3nica, t\u00edtulos de puestos de trabajo y terminolog\u00eda local, hasta la entrega verbal en el idioma local del cliente potencial (por ejemplo, \u00a1como californiano, amigo...!).<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el Nivel 2:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Realiza los cambios oportunos en los datos de la demostraci\u00f3n y la entrega verbal.<\/li>\n<\/ul>\n<p class=\"p3\"><b>Nivel 3 - Personalizaci\u00f3n basada en la informaci\u00f3n descubierta<\/b><\/p>\n<p class=\"p3\">Esto requiere tres pasos para completarse:<\/p>\n<ol class=\"ol1\">\n<li class=\"li3\">El descubrimiento debe ser <i>hecho<\/i>;<\/li>\n<li class=\"li3\">La informaci\u00f3n de descubrimiento debe ser <i>comunicado<\/i> (si no es la misma persona la que hace el descubrimiento y la demo);<\/li>\n<li class=\"li3\">La informaci\u00f3n de descubrimiento debe ser <i>incorporado<\/i> en la demo.<\/li>\n<\/ol>\n<p class=\"p3\">\u00bfSuena obvio?<span class=\"Apple-converted-space\">\u00a0 <\/span>Lamentablemente, he visto innumerables demostraciones en las que:<\/p>\n<ol class=\"ol1\">\n<li class=\"li3\">El descubrimiento nunca se hizo o fue insuficiente para influir en lo que se mostr\u00f3 en la demo;<\/li>\n<li class=\"li3\">El descubrimiento se hizo (por otra persona) pero nunca se comunic\u00f3 al presentador de la demostraci\u00f3n;<\/li>\n<li class=\"li3\">El descubrimiento se hizo pero fue <i>ignorado<\/i> en la demostraci\u00f3n resultante.<\/li>\n<\/ol>\n<p class=\"p3\">Muy sencillo, <a href=\"https:\/\/greatdemo.com\/es\/evaluar-niveles-de-habilidad-de-descubrimiento-como-califica-su-equipo-actualizado-y-ampliado\/\"><span class=\"s2\">descubrimiento suficiente<\/span><\/a> ofrece orientaci\u00f3n sobre qu\u00e9 funciones incluir en la demostraci\u00f3n y cu\u00e1les no. <i>omitir<\/i>.<span class=\"Apple-converted-space\">\u00a0 <\/span>Si las demostraciones de su equipo siguen el mismo camino independientemente de lo aprendido en el descubrimiento, entonces no han alcanzado el Nivel 3.<\/p>\n<p class=\"p3\">Una observaci\u00f3n:<span class=\"Apple-converted-space\">\u00a0 <\/span>Es incre\u00edblemente insultante para los clientes potenciales que han invertido en una conversaci\u00f3n de descubrimiento sustantiva con un proveedor que ese proveedor <i>ignora<\/i> la informaci\u00f3n sobre descubrimientos facilitada <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 3:<\/p>\n<p class=\"p3\">A) Se ha completado el descubrimiento suficiente;<\/p>\n<p class=\"p3\">B) Se comunica informaci\u00f3n sobre el descubrimiento;<\/p>\n<p class=\"p3\">C) Presenta o <i>no<\/i> presentar capacidades en consonancia con la informaci\u00f3n recopilada sobre descubrimientos.<\/p>\n<p class=\"p3\"><b>Nivel 4 - Comunica el valor empresarial<\/b><\/p>\n<p class=\"p3\">La queja n\u00famero 1 de los responsables de preventa y ventas sobre las demos de sus equipos es que \"no comunican valor de negocio...\"<span class=\"Apple-converted-space\">\u00a0 <\/span>Y para comunicar el valor empresarial, los equipos tienen que saber en qu\u00e9 consiste para sus clientes potenciales.<\/p>\n<p class=\"p3\">Valor empresarial gen\u00e9rico: <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Caso 1:<span class=\"Apple-converted-space\">\u00a0 <\/span>En el caso m\u00e1s sencillo, los equipos de preventa y ventas deben ser capaces de articular las ventajas intangibles de su soluci\u00f3n.<span class=\"Apple-converted-space\">\u00a0 <\/span>Podr\u00eda formularse as\u00ed: \"Nuestro software le permite reducir el tiempo necesario para...\".<span class=\"Apple-converted-space\">\u00a0 <\/span>Francamente, esto es demasiado gen\u00e9rico y, en consecuencia, casi carece de sentido...<\/p>\n<p class=\"p3\">Caso 2:<span class=\"Apple-converted-space\">\u00a0 <\/span>Un poco mejor es comunicar los tipos de ganancias que se observan en el sector: \"Nuestros clientes informan de ahorros de entre 2 y 4 semanas en el tiempo de proceso...\".<span class=\"Apple-converted-space\">\u00a0 <\/span>Pero, \u00bfresonar\u00e1 esto con la perspectiva actual?<\/p>\n<p class=\"p3\">Caso 3:<span class=\"Apple-converted-space\">\u00a0 <\/span>Una mejora adicional es ser m\u00e1s espec\u00edfico: \"Otros clientes que son muy <i>similar<\/i> le informan de reducciones del proceso de 2-3 semanas...\". <span class=\"Apple-converted-space\">\u00a0 <\/span>Esto le parecer\u00e1 m\u00e1s relevante al cliente potencial actual, pero tenga en cuenta que las cifras son las siguientes <i>de otra persona<\/i>.<\/p>\n<p class=\"p3\">Valor empresarial espec\u00edfico:<\/p>\n<p class=\"p3\">Comunicar el valor empresarial espec\u00edfico del cliente potencial requiere (s\u00ed, lo has adivinado) \u00a1hacer descubrimiento...!<span class=\"Apple-converted-space\">\u00a0 <\/span>Durante el descubrimiento, cada vez que su cliente potencial \"admite dolor\", su trabajo consiste en <a href=\"https:\/\/greatdemo.com\/es\/hablemos-de-valor\/\"><span class=\"s2\">cuantifique<\/span><\/a> eso. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Cuando el cliente potencial diga: \"Tarda demasiado...\", tu respuesta debe ser en forma de dos preguntas:<\/p>\n<p class=\"p3\">1. \u00bfCu\u00e1nto se tarda hoy?<\/p>\n<p class=\"p3\">2. \u00bfCu\u00e1nto tiempo debe durar?<\/p>\n<p class=\"p3\">La diferencia es el Delta: una expresi\u00f3n simple y directa del valor.<span class=\"Apple-converted-space\">\u00a0 <\/span>Unas cuantas preguntas adicionales le permitir\u00e1n hacer las cuentas (\"maths\", para usted en el Reino Unido, etc.) para calcular declaraciones de valor empresarial significativas. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Un ejemplo:<\/p>\n<p class=\"p3\">Prospect afirma: \"Tarda demasiado...\".<\/p>\n<p class=\"p3\">Usted pregunta: \"\u00bfCu\u00e1nto tarda hoy?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>El cliente potencial responde: \"El proceso completo tarda actualmente 10 d\u00edas laborables...\".<\/p>\n<p class=\"p3\">Usted pregunta: \"\u00bfY qu\u00e9 le gustar\u00eda que fuera, qu\u00e9 tiene que ser?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>El cliente potencial responde: \"Tenemos que reducirlo a 2 d\u00edas laborables\".<\/p>\n<p class=\"p3\">Y t\u00fa sigues con: \"\u00bfY con qu\u00e9 frecuencia realizas este proceso?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>\"Cada dos semanas - 25 veces al a\u00f1o...\" es la respuesta. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Luego preguntas: \"\u00bfY cu\u00e1ntas personas se consumen hoy en este proceso?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>Prospect responde: \"10 funcionarios, es su \u00fanica funci\u00f3n\".<\/p>\n<p class=\"p3\">Por lo tanto, esta perspectiva podr\u00eda redistribuir 80% de este equipo a otras tareas, es decir, 8 ETC (equivalentes a tiempo completo). <i>tangible<\/i> y valor espec\u00edfico de realizar el cambio para <i>este<\/i> \u00a1Prospecto!<span class=\"Apple-converted-space\">\u00a0 <\/span>Esta informaci\u00f3n debe comunicarse y reforzarse a lo largo de toda la demostraci\u00f3n: es la fuerza motriz para realizar el cambio.<\/p>\n<p class=\"p3\">Metas, objetivos y resultados:<\/p>\n<p class=\"p3\">Por \u00faltimo, los profesionales de nivel 4 descubren las metas y objetivos empresariales generales de los clientes potenciales y alinean su discurso sobre el valor empresarial con estas metas y objetivos (\"Cuestiones empresariales cr\u00edticas\").<\/p>\n<p class=\"p3\">En el ejemplo anterior, cuando identificamos el valor de negocio espec\u00edfico para un proceso concreto, el profesional de nivel 4 deber\u00eda <i>tambi\u00e9n<\/i> han preguntado: \"<i>Por qu\u00e9<\/i> \u00bfnecesita mejorar su proceso? \u00bfcu\u00e1l es su objetivo para este proyecto?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>La respuesta del cliente potencial podr\u00eda ser algo as\u00ed: \"Nos han encargado aumentar nuestra productividad global en 10% y este proceso se identific\u00f3 como un \u00e1rea problem\u00e1tica clave...\".<span class=\"Apple-converted-space\">\u00a0 <\/span>As\u00ed, la cuesti\u00f3n empresarial cr\u00edtica es \"Aumentar la productividad en 10%\", y nos asegurar\u00edamos de incluirla en nuestro debate sobre el valor empresarial durante la demostraci\u00f3n.<\/p>\n<p class=\"p3\">En la metodolog\u00eda Great Demo!, incluimos el\/los problema(s) empresarial(es) cr\u00edtico(s) del cliente potencial <i>as\u00ed como<\/i> el valor empresarial espec\u00edfico en la Diapositiva de Situaci\u00f3n; volvemos a ellos cuando presentamos Ilustraciones; y los incluimos en nuestros Res\u00famenes.<span class=\"Apple-converted-space\">\u00a0 <\/span>La comunicaci\u00f3n coherente y precisa del valor empresarial es un factor cr\u00edtico para el \u00e9xito de las demostraciones, y puede ser un importante punto de diferenciaci\u00f3n entre proveedores.<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 4:<\/p>\n<p class=\"p3\">A) Presenta declaraciones gen\u00e9ricas de valor empresarial;<\/p>\n<p class=\"p3\">B) Presenta un valor empresarial tangible y espec\u00edfico para el cliente potencial;<\/p>\n<p class=\"p3\">C) Vincula el valor empresarial a la(s) cuesti\u00f3n(es) empresarial(es) cr\u00edtica(s).<\/p>\n<p class=\"p3\"><b>Nivel 5 - Gestiona y explora posibles preguntas<\/b><\/p>\n<p class=\"p3\">Este nivel consta de dos partes.<span class=\"Apple-converted-space\">\u00a0 <\/span>En primer lugar, evaluar y gestionar el flujo de preguntas y, en segundo lugar, explorar la intenci\u00f3n <i>detr\u00e1s de<\/i> preguntas de los prospectos. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Lograr la primera parte es un proceso din\u00e1mico de comprensi\u00f3n: \"\u00bfEs esto algo que necesito responder ahora o deber\u00eda aplazarlo hasta m\u00e1s tarde?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>El uso de un aparcamiento de preguntas es un indicador de <a href=\"https:\/\/greatdemo.com\/es\/perdido-en-la-maleza\/\"><span class=\"s2\">gesti\u00f3n eficaz de las preguntas<\/span><\/a>.<\/p>\n<p class=\"p3\">La segunda parte explora la <i>por qu\u00e9<\/i> detr\u00e1s de las preguntas de los prospectos.<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfEs inter\u00e9s serio?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfEs una \"mina terrestre\" colocada por un competidor?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfEs un criterio \"KO\" o un \"nice to have\"?<\/p>\n<p class=\"p3\">No s\u00e9 cu\u00e1ntas veces he o\u00eddo a un cliente potencial preguntar: \"\u00bfSu software puede hacer X?\", y el vendedor ha respondido: \"Por supuesto\", o \"No, pero tenemos una soluci\u00f3n; se la mostrar\u00e9...\".<\/p>\n<p class=\"p3\">En ambos casos, el vendedor perdi\u00f3 una importante oportunidad de pedir aclaraciones...<span class=\"Apple-converted-space\">\u00a0 <\/span>\"\u00bfQu\u00e9 importancia tiene esto para ti?\"<span class=\"Apple-converted-space\">\u00a0 <\/span>\"\u00bfQu\u00e9 motiv\u00f3 su pregunta?\"<span class=\"Apple-converted-space\">\u00a0 <\/span>\"\u00bfQu\u00e9 necesita conseguir con este tipo de capacidad?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>\"\u00bfCon qu\u00e9 frecuencia se utilizar\u00eda?\"<\/p>\n<p class=\"p3\">El profesional de nivel 5 investiga detenidamente las posibles preguntas. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 5:<\/p>\n<p class=\"p3\">A) Aplica los principios del aparcamiento;<\/p>\n<p class=\"p3\">B) Hace preguntas aclaratorias.<\/p>\n<p class=\"p3\"><b>Nivel 6 - Comunica las solicitudes de mejoras y nuevas funciones al producto<\/b><\/p>\n<p class=\"p3\">Los vendedores que trabajan con una oportunidad de gran valor a menudo expresan la necesidad urgente de una nueva funci\u00f3n para conseguir el negocio.<span class=\"Apple-converted-space\">\u00a0 <\/span>El personal de preventa tambi\u00e9n debe comunicar las necesidades de los clientes potenciales, pero con un poco m\u00e1s de moderaci\u00f3n y circunspecci\u00f3n...<\/p>\n<p class=\"p3\">Para la mayor\u00eda de las empresas de software, las solicitudes de nuevas funciones deben estar en consonancia con las hojas de ruta de productos dise\u00f1adas para abarcar mercados espec\u00edficos, y si la nueva funci\u00f3n deseada se aleja demasiado del camino, se convierte en una distracci\u00f3n costosa o algo peor (apartar a los desarrolladores del esfuerzo \"principal\"; requerir apoyo continuo para un solo cliente en lugar de satisfacer las necesidades de la mayor\u00eda). <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">En consecuencia, los profesionales de preventa (y ventas) deben registrar las solicitudes de caracter\u00edsticas con informaci\u00f3n adicional sobre la importancia relativa de la nueva capacidad y otra serie de par\u00e1metros.<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfQu\u00e9 ejemplos concretos hay?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfPermitir\u00e1 esto un nuevo espacio para nosotros?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfLo necesitamos para alcanzar la paridad competitiva?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfSuperar\u00e1 a nuestra competencia?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfLa solicitud procede de un cliente potencial o de varios?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfLa solicitud procede de un nuevo cliente potencial o de un cliente actual?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfLo ha solicitado realmente el cliente potencial o nos hemos dado cuenta (sobre el terreno) de que es necesario? <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">La mayor\u00eda de las empresas de software tienen procesos y par\u00e1metros espec\u00edficos para el registro de nuevas funciones.<span class=\"Apple-converted-space\">\u00a0 <\/span>El profesional de nivel 6 las comprende y registra las solicitudes en consecuencia.<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 6:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Las nuevas solicitudes de funciones incluyen casos de uso, valor relativo, importancia e informaci\u00f3n sobre alineaci\u00f3n.<\/li>\n<\/ul>\n<p class=\"p3\"><b>Nivel 7 - Utiliza preguntas tendenciosas para flanquear a la competencia y redise\u00f1ar la visi\u00f3n<\/b><\/p>\n<p class=\"p3\">Es un paso importante para alcanzar las pr\u00e1cticas del Nivel 7: la mayor\u00eda de los vendedores y preventas desconocen el uso de las Preguntas Sesgadas y la visi\u00f3n de reingenier\u00eda. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">A <a href=\"https:\/\/greatdemo.com\/es\/terrific-competitive-differentiation\/\"><span class=\"s2\">Pregunta tendenciosa<\/span><\/a> conduce al cliente potencial hacia una conclusi\u00f3n (l\u00f3gica), como la necesidad de su capacidad competitiva ventajosa.<span class=\"Apple-converted-space\">\u00a0 <\/span>En estos casos, la capacidad se introduce <i>verbalmente<\/i> - y s\u00f3lo se muestra cuando el cliente potencial acepta verla.<span class=\"Apple-converted-space\">\u00a0 <\/span>Tenga en cuenta que si se limita a mostrar capacidades que el cliente potencial no ha solicitado, corre el riesgo de \"<a href=\"https:\/\/greatdemo.com\/es\/25282-2\/\"><span class=\"s2\">volver a comprarlo<\/span><\/a>\".<\/p>\n<p class=\"p3\">El profesional de Nivel 7 tiene un almac\u00e9n de Preguntas tendenciosas listo para desplegar (tanto en descubrimiento como en demostraciones) y las introduce cuando es apropiado. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/greatdemo.com\/es\/evaluar-niveles-de-habilidad-de-descubrimiento-como-califica-su-equipo-actualizado-y-ampliado\/\">Reingenier\u00eda de la visi\u00f3n<\/a><\/span> es otro tema avanzado: es el proceso de ayudar a tu cliente potencial a ampliar su visi\u00f3n para abarcar la tuya en forma de las capacidades de tu oferta.<span class=\"Apple-converted-space\">\u00a0 <\/span>Un ejemplo es la diferencia entre un informe est\u00e1tico (la entrega actual del cliente potencial) y un cuadro de mandos din\u00e1mico con funciones de \"troceado\" y desglose.<span class=\"Apple-converted-space\">\u00a0 <\/span>Las preguntas tendenciosas son utilizadas con frecuencia por el personal de ventas y preventa de Level 7 para impulsar conversaciones de reingenier\u00eda de visi\u00f3n.<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 7:<\/p>\n<p class=\"p3\">A) Utiliza preguntas sesgadas;<\/p>\n<p class=\"p3\">B) Establece una visi\u00f3n redise\u00f1ada.<\/p>\n<p class=\"p3\"><b>Nivel 8 - Aplica t\u00e9cnicas narrativas para reforzar ideas clave<\/b><\/p>\n<p class=\"p3\">Junto a la \"comunicaci\u00f3n del valor empresarial\", la narraci\u00f3n de historias es quiz\u00e1 la siguiente mejora de las habilidades de demostraci\u00f3n m\u00e1s solicitada por los directores de ventas y preventa.<span class=\"Apple-converted-space\">\u00a0 <\/span>Pero \"envolver tu demo con una historia...\" no es una soluci\u00f3n sencilla ni eficaz.<span class=\"Apple-converted-space\">\u00a0 <\/span><a href=\"https:\/\/greatdemo.com\/es\/story-telling-in-demos\/\"><span class=\"s2\">Cuentacuentos<\/span><\/a> tiene que ver con la comunicaci\u00f3n <i>pegajosidad<\/i> - y la capacidad de sus clientes potenciales para recordar sus mensajes clave.<\/p>\n<p class=\"p3\">En consecuencia, la demo \"Un d\u00eda en la vida\" es <i>no<\/i> una historia eficaz - es s\u00f3lo un marco...<span class=\"Apple-converted-space\">\u00a0 <\/span>Los profesionales de nivel 8 utilizan historias cuando presentan sus puntos m\u00e1s importantes, conceptos cr\u00edticos y capacidades competitivas clave.<span class=\"Apple-converted-space\">\u00a0 <\/span>Las historias ayudan a que estas ideas sean memorables y permiten que se repitan con gran fidelidad dentro de la organizaci\u00f3n del cliente.<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 8:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Utiliza historias discretas para apoyar capacidades o conceptos clave.<\/li>\n<\/ul>\n<p class=\"p3\"><b>Nivel 9 - Diferencia la generaci\u00f3n de visiones de los escenarios de pruebas t\u00e9cnicas<\/b><\/p>\n<p class=\"p3\">Los responsables de preventa informan de que hasta 30% de las demostraciones de su equipo se desperdician, por ejemplo, ofreciendo Harbor Tours a clientes potenciales no cualificados.<span class=\"Apple-converted-space\">\u00a0 <\/span>Cuando los clientes potenciales hacen clic en el bot\u00f3n \"Reservar una demostraci\u00f3n\" de los sitios web de los proveedores, a menudo s\u00f3lo quieren ver \"el arte de lo posible\", no todos los detalles.<\/p>\n<p class=\"p3\">Muchos vendedores dicen: \"No podr\u00edamos <i>posiblemente<\/i> presentar una demo en menos de una hora...\". Lamentablemente, es probable que sean 50 minutos demasiado para lo que quieren ver sus clientes potenciales.<span class=\"Apple-converted-space\">\u00a0 <\/span>Est\u00e1n desalineados.<\/p>\n<p class=\"p3\">Los profesionales de nivel 9 lo reconocen y dominan la capacidad de ofrecer <i>lo justo<\/i> demo para generar visi\u00f3n <i>y<\/i> para permitir que tenga lugar una conversaci\u00f3n de descubrimiento.<span class=\"Apple-converted-space\">\u00a0 <\/span>Han aprendido a utilizar ejemplos de historias de \u00e9xito de clientes y pantallas de entregables clave (Historias de \u00c9xito Informales e Ilustraciones, respectivamente) para lograr estos objetivos.<span class=\"Apple-converted-space\">\u00a0 <\/span>Estos profesionales satisfacen suavemente (\u00a1pero con firmeza!) el deseo de sus clientes potenciales de ver \"el arte de lo posible\" y luego pasan a conversaciones de descubrimiento.<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 9:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Aplica las competencias pertinentes (por ejemplo, la <a href=\"https:\/\/greatdemo.com\/es\/el-menu-aproxima-una-tecnica-de-auto-rescate-verdaderamente-terrifica\/\"><span class=\"s2\">Enfoque del men\u00fa<\/span><\/a> y <a href=\"https:\/\/greatdemo.com\/es\/vision-generation-demos\/\"><span class=\"s2\">Demostraciones de Vision Generation<\/span><\/a>).<\/li>\n<\/ul>\n<p class=\"p3\"><b>Nivel 10 - Captura y permite la reutilizaci\u00f3n de escenarios de demostraci\u00f3n con \u00e9xito<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p class=\"p3\">A medida que el personal de preventa y ventas madura, reconoce la importancia del altruismo y la capacitaci\u00f3n mutua: compartir lo que ha funcionado (y lo que no) con sus compa\u00f1eros genera un c\u00edrculo virtuoso de retroalimentaci\u00f3n, que permite a los individuos aprovechar las experiencias m\u00e1s amplias del equipo.<\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/greatdemo.com\/es\/cuatro-oportunidades-para-cosechar-el-valor-de-las-historias-de-exito-informales\/\">\u00c9xitos informales<\/a><\/span> forman parte de la savia de una organizaci\u00f3n y son utilizados por vendedores y preventas experimentados como parte integrante de sus procesos.<span class=\"Apple-converted-space\">\u00a0 <\/span>Suelen empezar con una frase como: \"Perm\u00edtame compartir c\u00f3mo otro cliente, muy similar a usted, resolvi\u00f3 esto...\".<span class=\"Apple-converted-space\">\u00a0 <\/span>El resto de la historia (a menudo un \"viaje del h\u00e9roe\") describe c\u00f3mo se superaron los retos del cliente gracias a la oferta del proveedor.<\/p>\n<p class=\"p3\">Estos bucles de retroalimentaci\u00f3n positiva suelen comenzar de manera informal con discusiones del equipo de proveedores posteriores a la demostraci\u00f3n sobre \"\u00bfqu\u00e9 ha ido bien?\", \"\u00bfqu\u00e9 no ha ido bien?\" y \"\u00bfqu\u00e9 podr\u00edamos haber hecho mejor o de otra manera?\".<span class=\"Apple-converted-space\">\u00a0 <\/span>Formalizar este proceso para convertir las revisiones posteriores a las demostraciones en un h\u00e1bito estructurado y regular es un indicador clave de las pr\u00e1cticas de nivel 10.<\/p>\n<p class=\"p3\">Ahora, imagina una sala de 50 preventas y vendedores en una reuni\u00f3n de inicio de enero...<span class=\"Apple-converted-space\">\u00a0 <\/span>A cada uno se le ha pedido que escriba una historia de \u00e9xito de un cliente que haya experimentado, una sola historia cada uno.<span class=\"Apple-converted-space\">\u00a0 <\/span>10 minutos despu\u00e9s env\u00edan esas historias a una persona de habilitaci\u00f3n que las recopila en una biblioteca.<span class=\"Apple-converted-space\">\u00a0 <\/span>De repente, todo el mundo tiene 49 <i>nuevo<\/i> historias de \u00e9xito en las que inspirarse y utilizarlas en sus esfuerzos de venta y preventa: \u00a1qu\u00e9 delicia!<\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/greatdemo.com\/es\/por-que-compraron-fabuloso-combustible-para-ventas-presenciales-y-exito-de-clientes\/\">Recoger historias de \u00e9xito informales<\/a><\/span> \u00a1en Gran Demo! El formato de diapositivas de situaci\u00f3n, junto con las ilustraciones y los men\u00fas que las acompa\u00f1an, permite realizar demostraciones de generaci\u00f3n de visi\u00f3n para todo el equipo, adem\u00e1s de proporcionar ejemplos magn\u00edficos de c\u00f3mo son los prospectos buenos y bien cualificados: la \"idoneidad\" de los prospectos.<span class=\"Apple-converted-space\">\u00a0 <\/span>Estas plantillas amplifican y aceleran r\u00e1pidamente los procesos de venta y preventa, al tiempo que reducen (de forma bastante dr\u00e1stica) el n\u00famero de demostraciones desperdiciadas. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 10:<\/p>\n<p class=\"p3\">A) Realiza revisiones peri\u00f3dicas y estructuradas despu\u00e9s de la demostraci\u00f3n;<\/p>\n<p class=\"p3\">B) Presenta historias de \u00e9xito informales e ilustraciones adjuntas a la biblioteca corporativa;<\/p>\n<p class=\"p3\">C) Bonificaci\u00f3n por presentar men\u00fas.<\/p>\n<p class=\"p3\"><b>Nivel 11 - Aplica estas habilidades a la amplia gama de escenarios de demostraci\u00f3n requeridos<\/b><\/p>\n<p class=\"p3\">El personal de preventa y ventas de nivel b\u00e1sico suele considerar a los \"clientes potenciales\" como el \u00fanico p\u00fablico para sus demostraciones.<span class=\"Apple-converted-space\">\u00a0 <\/span>A medida que adquieren m\u00e1s experiencia, se dan cuenta de que hay una gama sorprendentemente amplia de demostraciones que se les piden, para clientes potenciales, clientes existentes, escenarios internos, y para 3<sup>rd<\/sup> partidos.<span class=\"Apple-converted-space\">\u00a0 <\/span>Cada una de ellas requiere comprender los objetivos de la demostraci\u00f3n y los intereses espec\u00edficos de la audiencia.<\/p>\n<p class=\"p3\">Algunos ejemplos:<\/p>\n<p class=\"p3\">- Centro de Informaci\u00f3n Ejecutiva Demos:<span class=\"Apple-converted-space\">\u00a0 <\/span>A menudo se presenta a ejecutivos de clientes potenciales o clientes que desean una comprensi\u00f3n de alto nivel de las capacidades y los resultados actuales y futuros.<\/p>\n<p class=\"p3\">- Demostraciones para terceros:<span class=\"Apple-converted-space\">\u00a0 <\/span>Una comprensi\u00f3n clara de \"\u00bfQu\u00e9 hay para ellos?\" (\"WIIFTs\") es clave para determinar qu\u00e9 mostrar...<\/p>\n<p class=\"p3\">- Socios de canal y revendedores:<span class=\"Apple-converted-space\">\u00a0 <\/span>Su objetivo es que sus ofertas sean las <i>preferido<\/i> productos para que sus socios los vendan, y hacer que sean f\u00e1ciles de vender, f\u00e1ciles de comprar... <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">- Demostraciones internas:<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfFormamos a los nuevos o a los ya existentes?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfTrabaja con gente de productos? <span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfMostrar a nuestros colegas una nueva forma de presentar las capacidades?<\/p>\n<p class=\"p3\">- \u00bfQu\u00e9 compartimos con los Campeones de nuestros prospectos frente al balance de sus equipos?<\/p>\n<p class=\"p3\">- \u00bfC\u00f3mo debemos presentar nuestro software a los clientes potenciales de la Adopci\u00f3n Temprana frente a los de la Mayor\u00eda Temprana frente a los de la Mayor\u00eda Tard\u00eda?<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00bfQu\u00e9 nivel de detalle o de prueba quiere o necesita cada grupo?<\/p>\n<p class=\"p3\">- \u00bfC\u00f3mo tratamos a grupos numerosos con distintos cargos en una misma reuni\u00f3n de demostraci\u00f3n?<\/p>\n<p class=\"p3\">- \u00bfQu\u00e9 hay de las demostraciones para clientes existentes que contemplan <a href=\"https:\/\/greatdemo.com\/es\/ampliacion-y-renovacion-demos\/\"><span class=\"s2\">ampliar sus licencias<\/span><\/a>? <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">- \u00bfC\u00f3mo podemos utilizar <a href=\"https:\/\/greatdemo.com\/es\/almuerzo-aprendizaje-demos\/\"><span class=\"s2\">Almuerzo y formaci\u00f3n<\/span><\/a> \u00bfdemostraciones?<\/p>\n<p class=\"p3\">- \u00bfC\u00f3mo queremos estructurar nuestro <a href=\"https:\/\/greatdemo.com\/es\/mejores-practicas-en-ferias\/\"><span class=\"s2\">feria de muestras<\/span><\/a> \u00bfdemostraciones?<\/p>\n<p class=\"p3\">- C\u00f3mo crear demostraciones automatizadas y grabadas: \u00bfqu\u00e9 hay que incluir y c\u00f3mo hay que producirlas?<\/p>\n<p class=\"p3\">Los profesionales de nivel 11 que tienen \u00e9xito aplican un enfoque estructurado a sus demostraciones, teniendo en cuenta los objetivos de la demostraci\u00f3n (para ambas partes), los miembros del p\u00fablico y sus intereses espec\u00edficos, as\u00ed como la naturaleza de la reuni\u00f3n y el lugar de celebraci\u00f3n.<span class=\"Apple-converted-space\">\u00a0 <\/span>Tambi\u00e9n reconocen que cada escenario, aunque \u00fanico en principio, puede abordarse mejor con determinados componentes de demostraci\u00f3n reutilizables.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 11:<\/p>\n<p class=\"p3\">A) Aplica las habilidades aprendidas a la amplia gama de escenarios de demostraci\u00f3n requeridos, incluyendo prospectos que ocupan diferentes porciones de la Curva de Adopci\u00f3n Tecnol\u00f3gica, nuevos productos, Centros de Informaci\u00f3n Ejecutiva, ciclos de ventas transaccionales, oportunidades de expansi\u00f3n, sesiones de almuerzo y aprendizaje, ferias comerciales, demostraciones para analistas y terceros, Socios de Canal y Revendedores, y otros escenarios;<\/p>\n<p class=\"p3\">B) Reconoce y aprovecha la reutilizaci\u00f3n de componentes de demostraci\u00f3n.<\/p>\n<p class=\"p3\"><b>Nivel 12 - Integra, alinea y aprovecha las destrezas en una metodolog\u00eda de demostraci\u00f3n cohesionada.<\/b><\/p>\n<p class=\"p3\">Los objetivos aqu\u00ed son la amplificaci\u00f3n y el escalado: \u00a1aqu\u00ed es donde se pueden conseguir los mayores beneficios...!<\/p>\n<p class=\"p3\">Los profesionales experimentados en preventa y ventas de Level 11 se dan cuenta de que muchas de sus habilidades individuales y activos de demostraci\u00f3n pueden reutilizarse, combinarse y reutilizarse, lo que proporciona un apalancamiento y una eficiencia (potencialmente enormes) en sus procesos.<span class=\"Apple-converted-space\">\u00a0 <\/span>Esta es la esencia de la metodolog\u00eda de demostraci\u00f3n.<\/p>\n<p class=\"p3\">Una Metodolog\u00eda de Demostraci\u00f3n es un conjunto integrado y coherente de componentes que se interconectan, aprovechan y apoyan mutuamente, posibilitando procesos, gu\u00edas, movimientos coordinados, coherencia, seguimiento, medici\u00f3n y asesoramiento estructurado.<span class=\"Apple-converted-space\">\u00a0 <\/span>La metodolog\u00eda aborda tres cuestiones clave:<\/p>\n<p class=\"p3\">1. Por qu\u00e9 - por qu\u00e9 hacer las cosas de una determinada manera<\/p>\n<p class=\"p3\">2. Qu\u00e9 - qu\u00e9 debe hacerse<\/p>\n<p class=\"p3\">3. C\u00f3mo - c\u00f3mo y cu\u00e1ndo ejecutar habilidades espec\u00edficas - instrucciones expl\u00edcitas<\/p>\n<p class=\"p3\">La metodolog\u00eda permite ense\u00f1ar y practicar destrezas, tanto individualmente <i>y<\/i> como componentes integrados.<span class=\"Apple-converted-space\">\u00a0 <\/span>En la metodolog\u00eda Great Demo!, por ejemplo, las Historias de \u00c9xito Informales alimentan las Demostraciones de Generaci\u00f3n de Visi\u00f3n y los Men\u00fas asociados, apoyando una variedad de escenarios de demostraci\u00f3n (como solicitudes de \"mu\u00e9streme s\u00f3lo una demostraci\u00f3n\" de clientes potenciales, demostraciones del Centro de Informaci\u00f3n Ejecutiva, demostraciones para 3<sup>rd<\/sup> partidos y muchos otros).<span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p>\n<p class=\"p3\">Curiosamente, el vicepresidente de habilitaci\u00f3n de uno de nuestros clientes de Great Demo! se\u00f1al\u00f3 que \"la metodolog\u00eda <i>permite<\/i> habilitaci\u00f3n...!\"<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00a1Una perspectiva perspicaz y provocadora...!<\/p>\n<p class=\"p3\">Medida(s) para alcanzar el nivel 12:<\/p>\n<p class=\"p3\">A) Funciona como un equipo o una organizaci\u00f3n y no como individuos;<\/p>\n<p class=\"p3\">B) Eval\u00faa y aprovecha <a href=\"https:\/\/greatdemo.com\/es\/demo-capital-subutilizado-subvalorado-y-a-menudo-insuficiente\/\"><span class=\"s2\">capital de demostraci\u00f3n<\/span><\/a> que apoye y permita la amplificaci\u00f3n y el escalado;<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">C) Establece objetivos y realiza un seguimiento de los par\u00e1metros para mejorar el rendimiento y la eficacia del equipo;<\/p>\n<p class=\"p3\">D) Proporciona formaci\u00f3n estructurada a los nuevos empleados y desarrollo continuo de los miembros del equipo;<\/p>\n<p class=\"p3\">E) Evoluciona y afina activamente la metodolog\u00eda de acuerdo con los objetivos y la cultura de la empresa.<\/p>\n<p class=\"p3\">Las organizaciones que alcanzan el nivel 12 disfrutan de m\u00e9tricas de escalado y amplificaci\u00f3n notables, y establecen ventajas competitivas sustanciales frente a sus hom\u00f3logas.<\/p>\n<p class=\"p3\"><b>Pero espere: \u00a1hay m\u00e1s!<\/b><\/p>\n<p class=\"p3\">Tenga en cuenta que tambi\u00e9n hay un Nivel Cero, que realmente deber\u00eda considerarse la l\u00ednea de base para todas las demostraciones y presentaciones: <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Nivel 0:<span class=\"Apple-converted-space\">\u00a0 <\/span>Atrae e impulsa la interactividad (con demostraciones virtuales y presenciales, seg\u00fan proceda). <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">\u00a1Por desgracia, muchos presentadores ni siquiera alcanzan este nivel...!<span class=\"Apple-converted-space\">\u00a0 <\/span>Demasiadas demostraciones empiezan con la frase \"\u00bfPuedes ver mi rat\u00f3n?\", seguida de 60 minutos de clic, clic, clic... y cuando el presentador pregunta: \"\u00bfAlguna pregunta?\", las respuestas suelen ser: \"No, no pasa nada...\" o \"Chirp-chirp-chirp-chirp...\".<\/p>\n<p class=\"p3\">En el caso de las demostraciones virtuales, herramientas como Gong y Refract ofrecen \"interruptores de orador\" y m\u00e9tricas de \"relaci\u00f3n entre conversaci\u00f3n y escucha\" para ayudar a los presentadores a evaluar la ejecuci\u00f3n de sus demostraciones.<\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/www.gong.io\/blog\/sales-demos\/\" target=\"_blank\" rel=\"noopener\">Medida(s)<\/a><\/span> para alcanzar el nivel 0:<\/p>\n<p class=\"p3\">A) En las demostraciones, la proporci\u00f3n entre la conversaci\u00f3n y la escucha de los ponentes es de casi 65:45 (46:54 en las llamadas de descubrimiento);<\/p>\n<p class=\"p3\">B) Los cambios de altavoz se producen cada 76 segundos, por t\u00e9rmino medio.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\"><b>M\u00e1s de doce niveles de destrezas de demostraci\u00f3n<\/b><\/p>\n<p class=\"p3\">Nivel 0: Atrae e impulsa la interactividad.<\/p>\n<p class=\"p3\">Nivel 1:<span class=\"Apple-converted-space\">\u00a0 <\/span>Sigue el gui\u00f3n de demostraci\u00f3n \"est\u00e1ndar\".<\/p>\n<p class=\"p3\">Nivel 2:<span class=\"Apple-converted-space\">\u00a0 <\/span>Personaliza en funci\u00f3n del mercado\/industria del cliente potencial.<\/p>\n<p class=\"p3\">Nivel 3:<span class=\"Apple-converted-space\">\u00a0 <\/span>Personaliza en funci\u00f3n de la informaci\u00f3n descubierta.<\/p>\n<p class=\"p3\">Nivel 4: Comunica el valor empresarial.<\/p>\n<p class=\"p3\">Nivel 5:<span class=\"Apple-converted-space\">\u00a0 <\/span>Gestiona y explora las cuestiones relativas a los prospectos.<\/p>\n<p class=\"p3\">Nivel 6: Comunica al producto las solicitudes de mejoras y nuevas funciones.<\/p>\n<p class=\"p3\">Nivel 7:<span class=\"Apple-converted-space\">\u00a0 <\/span>Utiliza preguntas tendenciosas para superar a la competencia y redise\u00f1ar la visi\u00f3n.<\/p>\n<p class=\"p3\">Nivel 8: Aplica t\u00e9cnicas narrativas para reforzar las ideas clave.<\/p>\n<p class=\"p3\">Nivel 9: Diferencia la Generaci\u00f3n de Visiones de los escenarios de Pruebas T\u00e9cnicas.<\/p>\n<p class=\"p3\">Nivel 10: Captura y reutiliza los casos de \u00e9xito de las demostraciones.<\/p>\n<p class=\"p3\">Nivel 11: Aplica estas competencias a la amplia gama de situaciones de demostraci\u00f3n requeridas.<\/p>\n<p class=\"p3\">Nivel 12: Integra, alinea y aprovecha las habilidades anteriores en una metodolog\u00eda de demostraci\u00f3n cohesionada.<\/p>\n<p class=\"p3\">A falta de este tipo de an\u00e1lisis, la mayor\u00eda de los vendedores y preventas veteranos, cuando se les pregunta, se posicionan como \"avanzados\" o \"expertos\" en la preparaci\u00f3n y realizaci\u00f3n de demostraciones.<span class=\"Apple-converted-space\">\u00a0 <\/span>De hecho, cuando pregunt\u00e9 a una jefa de preventa sobre su equipo, me dijo: \"Bueno, yo dir\u00eda que s\u00f3lo 20% de los veteranos son realmente buenos; los dem\u00e1s...\". <i>piense en<\/i> son buenos, pero les queda mucho camino por recorrer...\".<\/p>\n<p class=\"p3\">Lamentablemente, la mayor\u00eda de las personas y equipos operan hoy en los niveles 2 y 3.<span class=\"Apple-converted-space\">\u00a0 <\/span>Utilice los niveles de este art\u00edculo para evaluar su situaci\u00f3n actual y la de su equipo. <i>desea<\/i> a ser), tal vez ha llegado el momento de <a href=\"https:\/\/greatdemo.com\/es\/talleres\/\"><span class=\"s2\">nivel superior<\/span><\/a> su conjunto de competencias y avanzar hacia una verdadera adopci\u00f3n de la metodolog\u00eda.<\/p>\n<p class=\"p3\">Copyright \u00a9 2021 The Second Derivative - Todos los derechos reservados.<\/p>","protected":false},"excerpt":{"rendered":"<p>Muchos profesionales de la preventa y las ventas afirman que son expertos en demostraciones, pero \u00bflo son?  He aqu\u00ed un m\u00e9todo sencillo para evaluar su situaci\u00f3n y la de su equipo, basado en doce niveles de competencia creciente: los Doce Niveles de Habilidades de Demostraci\u00f3n.<\/p>","protected":false},"author":2,"featured_media":26262,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14,8,9,17,13],"tags":[6,7],"class_list":["post-27500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advanced_topics","category-great-demo-blog","category-growth_development","category-justifying_training","category-mostly_for_managers","tag-articles","tag-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts\/27500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/comments?post=27500"}],"version-history":[{"count":0,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts\/27500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/media\/26262"}],"wp:attachment":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/media?parent=27500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/categories?post=27500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/tags?post=27500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}