{"id":25295,"date":"2020-07-30T17:54:40","date_gmt":"2020-07-30T17:54:40","guid":{"rendered":"https:\/\/greatdemo.com\/?p=25295"},"modified":"2023-02-01T17:54:11","modified_gmt":"2023-02-01T17:54:11","slug":"ignition-demos-a-rather-huge-unmet-need-and-opportunity","status":"publish","type":"post","link":"https:\/\/greatdemo.com\/es\/ignition-demos-a-rather-huge-unmet-need-and-opportunity\/","title":{"rendered":"Demostraciones Ignition: una enorme necesidad y oportunidad insatisfechas"},"content":{"rendered":"<p style=\"text-align: left;\"><strong style=\"font-size: 14px; text-align: left;\">Sinopsis:<\/strong><\/p>\n<p><span style=\"color: #000000;\">Los prospectos que \"s\u00f3lo navegan\" est\u00e1n desatendidos en los enfoques de ventas tradicionales, pero consumen valiosos y costosos recursos de preventa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Proponemos:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Un nuevo tipo de Demo de Generaci\u00f3n de Visi\u00f3n: \"Demostraciones de Ignici\u00f3n\" para proporcionar la chispa para el motor que impulsa el viaje del prospecto hasta convertirse en cliente;<\/span><\/li>\n<li><span style=\"color: #000000;\">Un nuevo tipo de empleado de cara al cliente: Un \"consultor de navegaci\u00f3n\" que aporte esa chispa y entable una conversaci\u00f3n inicial con el cliente potencial.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Ventajas:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Los valiosos recursos de preventa no se malgastan ofreciendo demostraciones generales a clientes potenciales que \"s\u00f3lo est\u00e1n mirando\" y no tienen intenci\u00f3n de comprar a corto plazo.<\/span><\/li>\n<li><span style=\"color: #000000;\">Los BDR y SDR no pierden el tiempo tratando de calificar y fijar reuniones para sus correspondientes vendedores con estos prospectos \"Just Browsing\" de manera similar.<\/span><\/li>\n<li><span style=\"color: #000000;\">Los vendedores no pierden el tiempo en reuniones organizadas por los BDR y SDR con clientes potenciales que \"s\u00f3lo navegan\" y que han superado los criterios de cualificaci\u00f3n.<\/span><\/li>\n<li><span style=\"color: #000000;\">El personal de preventa y atenci\u00f3n al cliente de nivel b\u00e1sico comienza como consultores de navegaci\u00f3n y: <\/span>\n<ul>\n<li><span style=\"color: #000000;\">Aprenda a involucrar a los clientes potenciales en compromisos de bajo riesgo;<\/span><\/li>\n<li><span style=\"color: #000000;\">Aprender a articular los casos de uso de alta probabilidad para sus ofertas;<\/span><\/li>\n<li><span style=\"color: #000000;\">Aprenda a entablar conversaciones significativas con clientes potenciales;<\/span><\/li>\n<li><span style=\"color: #000000;\">Alcanzar una competencia b\u00e1sica con sus productos y sistemas (por ejemplo, su CRM);<\/span><\/li>\n<li><span style=\"color: #000000;\">A medida que estos miembros del personal maduran, pueden ser \"recolectados\" en proyectos activos de ventas y posventa como miembros de equipos de preventa y de \u00e9xito del cliente.<\/span><\/li>\n<\/ul>\n<\/li>\n<li><span style=\"color: #000000;\">Una cantidad razonable de informaci\u00f3n sobre el descubrimiento de clientes potenciales se recopila en una fase temprana, mucho antes de que el cliente potencial inicie el proceso de compra.<\/span><\/li>\n<li><span style=\"color: #000000;\">Los clientes potenciales se sentir\u00e1n apreciados y tendr\u00e1n una predisposici\u00f3n positiva hacia el vendedor.<\/span><\/li>\n<li><span style=\"color: #000000;\">El departamento de marketing tiene una visi\u00f3n m\u00e1s clara de los enfoques de marketing de nutrici\u00f3n\/trickle\/drip para estos clientes potenciales, lo que permite un movimiento m\u00e1s r\u00e1pido y\/o m\u00e1s seguro hacia la compra.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\"><strong>Argumentos<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Considere:  50% de los leads que generas est\u00e1n cualificados, pero no est\u00e1n listos para comprar ahora mismo....<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">\u00bfC\u00f3mo gestiona en sus procesos de venta a los clientes potenciales que no est\u00e1n listos para comprar?<\/span><\/li>\n<li><span style=\"color: #000000;\">\u00bfCu\u00e1ntas demostraciones realiza que son en gran medida una p\u00e9rdida de tiempo para usted, demostraciones para clientes potenciales que simplemente desean informaci\u00f3n, aquellos que \"s\u00f3lo est\u00e1n mirando\"?<\/span><\/li>\n<li><span style=\"color: #000000;\">\u00bfCon qu\u00e9 frecuencia entregas demos que repites una y otra vez, que probablemente podr\u00edan haber sido grabadas y reproducidas para esos clientes potenciales?<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">He aqu\u00ed una idea provocadora: invierta una peque\u00f1a cantidad de energ\u00eda en estas perspectivas -s\u00f3lo una chispa- para satisfacerlas <em>y<\/em> empezar a moverlos hacia un proceso de compra.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a1An\u00edmate! <\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Lo que se necesita son demostraciones que enciendan una chispa en la mente del cliente potencial, \"demostraciones de encendido\", que generen una peque\u00f1a llama.  El est\u00edmulo continuado a trav\u00e9s del marketing de alimentaci\u00f3n, goteo y goteo aviva las llamas, a\u00f1ade le\u00f1a y, con el tiempo, desarrolla un fuego que exige atenci\u00f3n y se convierte en una realidad. <em>real<\/em> oportunidad.<\/span><\/p>\n<p><span style=\"color: #000000;\">En la mayor\u00eda de las organizaciones, estas importantes demostraciones reciben poco o ning\u00fan apoyo: tradicionalmente se conocen como demostraciones de marketing y educativas.<\/span><\/p>\n<p><span style=\"color: #000000;\">\"\u00bfQu\u00e9?\", te oigo gritar... \"Cre\u00eda que nos hab\u00edas dicho espec\u00edficamente <em>no<\/em> para hacer demostraciones educativas y visitas al puerto...\".<\/span><\/p>\n<p><span style=\"color: #000000;\">Efectivamente, y sigue siendo correcto.<\/span><\/p>\n<p><span style=\"color: #000000;\">El personal de preventa cualificado no deber\u00eda invertir tiempo en demostraciones educativas individuales con los clientes potenciales, sino <em>alguien <\/em>o <em>algo <\/em>deber\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tradicionalmente, este es el trabajo de marketing, pero la mayor\u00eda de las organizaciones de marketing no tienen el ancho de banda o los recursos de personal para involucrar a los prospectos directamente.  Hoy en d\u00eda, a los clientes potenciales se les suele presentar:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Una demostraci\u00f3n grabada alojada en un sitio web que presupone que todos los clientes son iguales (y que suele ser insuficiente para los clientes potenciales que desean conocer la oferta del proveedor);<\/span><\/li>\n<li><span style=\"color: #000000;\">Un formulario de \"Contacto con ventas\" del sitio web que activa un proceso de cualificaci\u00f3n SDR\/DBDR;<\/span><\/li>\n<li><span style=\"color: #000000;\">Un bot\u00f3n \"Reserve una demostraci\u00f3n\" en el sitio web\" que <em>tambi\u00e9n<\/em> desencadena el mismo proceso de cualificaci\u00f3n SDR\/DBDR.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Esto es lo que suele ocurrir con nuestros clientes potenciales \"a simple vista\"...<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Todo es cuesti\u00f3n de ventas, \u00bfverdad?<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">La mayor\u00eda de las demostraciones en directo se centran en hacer avanzar al cliente a trav\u00e9s de un proceso de venta y asumen que, o bien:<\/span><\/p>\n<p><span style=\"color: #000000;\">Caso 1: El cliente busca activamente una soluci\u00f3n, o<\/span><\/p>\n<p><span style=\"color: #000000;\">Caso 2: El cliente <em>necesita<\/em> buscar activamente una soluci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el primer caso, el cliente se pone en contacto con uno o varios proveedores en una fase muy avanzada del proceso de compra, con el fin de comparar soluciones, precios, idoneidad, credenciales del proveedor, etc.  Esto es t\u00edpico de los procesos de ventas entrantes, en los que el cliente busca activamente una soluci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el segundo caso, un vendedor o BDR\/SDR trabaja para convencer al cliente de que el cliente <em>tiene<\/em> un problema que exige una soluci\u00f3n r\u00e1pida, con la expectativa de que el cliente inicie un proceso de compra una vez que se haya dado cuenta de la magnitud del problema y de que el tiempo es cr\u00edtico.  Esto es t\u00edpico de los procesos de ventas salientes.<\/span><\/p>\n<p><span style=\"color: #000000;\">En ambos casos se presupone que el cliente seguir\u00e1 una v\u00eda de compra a trav\u00e9s de uno de los siguientes resultados:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Comprando con nosotros.<\/span><\/li>\n<li><span style=\"color: #000000;\">Comprando a otra persona.<\/span><\/li>\n<li><span style=\"color: #000000;\">Optar por no hacer nada (\"Ninguna decisi\u00f3n\").<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Por consiguiente, cuando un cliente hace clic en el bot\u00f3n \"Ver una demostraci\u00f3n\" del sitio web de un proveedor, se supone que est\u00e1 en proceso de compra (caso 1: b\u00fasqueda activa de una soluci\u00f3n).  Por parte del vendedor, el siguiente paso suele ser que un SDR o BDR se ponga en contacto con el cliente para cualificar la oportunidad, concertar una reuni\u00f3n con un vendedor y hacer que el cliente avance por el proceso de ventas del vendedor.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el caso 2, si el equipo de ventas del vendedor consigue convencer al cliente para que estudie la posibilidad de abordar un problema desconocido hasta entonces o de menor prioridad, se sigue una trayectoria de ventas similar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pero, \u00bfqu\u00e9 ocurre en el caso 3?  \u00bfY si el cliente simplemente est\u00e1 explorando \"lo que hay ah\u00ed fuera\"?  \u00bfY si el cliente s\u00f3lo quiere saber qu\u00e9 es posible?<\/span><\/p>\n<p><span style=\"color: #000000;\">Entonces nos preguntamos: \"\u00bfHasta qu\u00e9 punto es un problema o una oportunidad?\".  Es grande...<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00bfEst\u00e1 la mayor\u00eda preparada para comprar?<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">No - o <em>todav\u00eda no<\/em>.  Consid\u00e9ralo:<\/span><\/p>\n<p><span style=\"color: #000000;\">\"Hasta el 95 por ciento de los clientes potenciales cualificados de su sitio web est\u00e1n all\u00ed para investigar y a\u00fan no est\u00e1n preparados para hablar con Ventas, sin embargo, hasta el 70 por ciento acabar\u00e1n compr\u00e1ndole a usted... o a sus competidores\". - Brian Carroll, autor de <a style=\"color: #000000;\" href=\"https:\/\/www.amazon.com\/Brian-Carroll-ebook\/dp\/B001E5KQN6\/ref=sr_1_2?dchild=1&amp;keywords=Lead+Generation+for+a+Complex+Sale&amp;qid=1595971088&amp;s=digital-text&amp;sr=1-2\" target=\"_blank\" rel=\"noopener\">Generaci\u00f3n de clientes potenciales para la venta compleja<\/a><\/span><\/p>\n<p><span style=\"color: #000000;\">Del mismo modo,<\/span><\/p>\n<p><span style=\"color: #000000;\">\"Seg\u00fan Gleanster Research, 50% de los leads que generas est\u00e1n cualificados, pero no listos para comprar ahora mismo\". - <a style=\"color: #000000;\" href=\"https:\/\/www.business.com\/articles\/youve-got-leads-why-arent-they-buying\/\" target=\"_blank\" rel=\"noopener\">Negocios.<\/a><a style=\"color: #000000;\" href=\"https:\/\/www.business.com\/articles\/youve-got-leads-why-arent-they-buying\/\" target=\"_blank\" rel=\"noopener\">com<\/a><\/span><\/p>\n<p><span style=\"color: #000000;\">Y,<\/span><\/p>\n<p><span style=\"color: #000000;\">\"La investigaci\u00f3n de Gartner muestra que la mayor\u00eda de los compradores de tecnolog\u00eda (59%) que realizan compras con regularidad responder\u00e1n \"siempre\" o \"a menudo\" a las campa\u00f1as de marketing de los vendedores cuando son <em>no<\/em> en un proceso de compra activo\".<\/span><\/p>\n<p><span style=\"color: #000000;\">Parece que es un <em>gran<\/em> problema (o una gran oportunidad)<\/span><\/p>\n<p><span style=\"color: #000000;\">Est\u00e1 claro que la mayor\u00eda de los visitantes del sitio web que hacen clic en el bot\u00f3n \"Reservar una demostraci\u00f3n\" son <em>no<\/em> listos para comprar- y los procesos de ventas tratan de descalificarlos lo m\u00e1s r\u00e1pidamente posible (mediante llamadas de cualificaci\u00f3n SDR\/BDR), dejando a los clientes potenciales interesados en conocer la oferta del vendedor con tres opciones:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Vaya a otro proveedor y vuelva a intentarlo.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">\u00bfResultado?  Este vendedor pierde la posibilidad de un cliente, \u00a1quiz\u00e1s para siempre...!<\/span><\/p>\n<ol start=\"2\">\n<li><span style=\"color: #000000;\"><em>Mentira<\/em> al SDR\/BDR en relaci\u00f3n con las preguntas de cualificaci\u00f3n, para que el cliente potencial pueda obtener la formaci\u00f3n y la informaci\u00f3n deseadas.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">\u00bfResultado?  El vendedor pierde el tiempo haciendo una demostraci\u00f3n para un cliente potencial que a\u00fan no est\u00e1 en modo de compra.<\/span><\/p>\n<ol start=\"3\">\n<li><span style=\"color: #000000;\">El cliente potencial responde con la verdad y es descalificado sin obtener la informaci\u00f3n deseada.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">\u00bfCu\u00e1l es el resultado?  El cliente potencial se a\u00f1ade (con suerte) a una lista de marketing de nutrici\u00f3n\/trickle\/drip y se le proporciona material de marketing peri\u00f3dico dise\u00f1ado para empujarlo hacia un proceso de compra activo.  Pero el cliente potencial no llega a ver una demostraci\u00f3n y queda insatisfecho.<\/span><\/p>\n<p><span style=\"color: #000000;\">Curiosamente, sigue trat\u00e1ndose en gran medida de <em>ver<\/em> una demostraci\u00f3n:<\/span><\/p>\n<p><span style=\"color: #000000;\">\"Las demostraciones siguen siendo populares entre los clientes potenciales, ya que los compradores suelen elegir una demostraci\u00f3n como forma r\u00e1pida de averiguar qu\u00e9 ofrece una soluci\u00f3n.  Una llamada a la acci\u00f3n que mencione una demostraci\u00f3n probablemente suscitar\u00e1 inter\u00e9s, ya que 58% de los compradores citaron las \"demostraciones\" como una llamada a la acci\u00f3n a la que responder\u00edan en una campa\u00f1a de marketing.\" - Gartner<\/span><\/p>\n<p><span style=\"color: #000000;\">Resumiendo:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">En dos de estos tres casos, el cliente potencial nunca ve una demostraci\u00f3n del vendedor;<\/span><\/li>\n<li><span style=\"color: #000000;\">Y en el tercer caso, mientras que la perspectiva <em>hace<\/em> ver una demostraci\u00f3n, a menudo se considera un esfuerzo in\u00fatil desde la perspectiva del vendedor.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">Tres resultados negativos.  \u00a1Propongamos algunas soluciones...!<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Un enfoque elegante para acoger a los clientes potenciales que \"s\u00f3lo navegan\".<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">En consecuencia, existe una ENORME brecha en nuestros procesos actuales de ventas y marketing.  Tiene que haber una forma de que los clientes potenciales vean una breve demostraci\u00f3n de lo que es posible -una Demostraci\u00f3n de Ignici\u00f3n- pero sin consumir tiempo de SDR\/BDR, ventas o preventa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tenemos que encontrar la manera de acoger a los 70%, los prospectos de \"S\u00f3lo navegar\".<\/span><\/p>\n<p><span style=\"color: #000000;\">He aqu\u00ed tres enfoques:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">No Touch - Uso de demostraciones automatizadas - Consultores de navegaci\u00f3n automatizada<\/span><\/li>\n<li><span style=\"color: #000000;\">Low Touch - utilizaci\u00f3n de recursos de nivel inferior - B\u00fasqueda de asesores<\/span><\/li>\n<li><span style=\"color: #000000;\">High Touch - mediante preventas, \u00e9xito del cliente o especialistas, formados espec\u00edficamente<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\"><strong>Sin contacto - Demostraciones automatizadas<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Se trata de un enfoque sencillo y muy elegante para dirigirse a sus clientes potenciales \"a simple vista\": proporci\u00f3neles una visi\u00f3n general de su oferta a trav\u00e9s de demostraciones de ignici\u00f3n grabadas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las grandes demostraciones de Ignition identifican con nitidez los problemas que pueden abordarse y las soluciones de alto nivel, haciendo hincapi\u00e9 en los aspectos m\u00e1s importantes. <em>resultados<\/em>.  Por ejemplo, mostrando <em>qu\u00e9<\/em> en el software abordar\u00eda o permitir\u00eda lo siguiente:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Mejora de la visibilidad mediante informes, cuadros de mando y alertas<\/span><\/li>\n<li><span style=\"color: #000000;\">Eliminaci\u00f3n de residuos y reducci\u00f3n del consumo de recursos<\/span><\/li>\n<li><span style=\"color: #000000;\">Aprovechamiento de oportunidades<\/span><\/li>\n<li><span style=\"color: #000000;\">Exploraci\u00f3n de excepciones<\/span><\/li>\n<li><span style=\"color: #000000;\">Mejora de la eficacia y la productividad<\/span><\/li>\n<li><span style=\"color: #000000;\">Reducci\u00f3n de riesgos<\/span><\/li>\n<li><span style=\"color: #000000;\">Identificaci\u00f3n de las causas<\/span><\/li>\n<li><span style=\"color: #000000;\">Mejoras en la comunicaci\u00f3n<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">Las grabaciones de unos minutos de duraci\u00f3n suelen ser suficientes para las ofertas m\u00e1s sencillas.  Las versiones en directo seguir\u00edan unas pautas similares, pero tambi\u00e9n tratar\u00edan de entablar una conversaci\u00f3n con el cliente potencial.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tenga en cuenta, no obstante, que las demostraciones de Ignition deben mostrar realmente su software, no pueden ser meros v\u00eddeos explicativos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para los proveedores con soluciones concisas y espec\u00edficas, las demostraciones de Ignition grabadas son un resumen de los problemas abordados, junto con las capacidades clave, las pantallas clave y los entregables clave proporcionados por la oferta.<\/span><\/p>\n<p><span style=\"color: #000000;\">El principal reto para que las demostraciones de Ignition sean eficaces es crear la grabaci\u00f3n con el <em>cliente<\/em> perspectiva en mente, abordando en primer lugar <em>qu\u00e9 <\/em>la oferta, y compartiendo s\u00f3lo la parte de la <em>c\u00f3mo<\/em> (ejecuci\u00f3n del proceso) seg\u00fan proceda.  Los resultados son lo primero; los pasos de los flujos de trabajo son secundarios.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los proveedores que tengan varias soluciones o soluciones que aborden varios conjuntos de necesidades (por ejemplo, proveedores de ERP y CRM) deben preparar minidemos para cada \u00e1rea de soluci\u00f3n o puesto de trabajo.<\/span><\/p>\n<p><span style=\"color: #000000;\">El acceso debe guiarse en consecuencia, por soluci\u00f3n, puesto de trabajo u otro mecanismo similar que permita a los interesados seleccionar por s\u00ed mismos sus intereses.  Cada minidemo deber\u00eda durar unos minutos.<\/span><\/p>\n<p><span style=\"color: #000000;\">(Tenga en cuenta que, en este caso, una visi\u00f3n general de \"talla \u00fanica\" sencillamente no funciona: volver\u00e1 a producir \"visitas al puerto\" de una hora de duraci\u00f3n, pero en formato grabado).<\/span><\/p>\n<p><span style=\"color: #000000;\">Tras una demostraci\u00f3n sin contacto, se presentan al cliente dos botones:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">\"Esto parece muy interesante - me gustar\u00eda entablar una llamada de ventas\" (\"S\u00ed, estoy en mi proceso de evaluaci\u00f3n y compra y me gustar\u00eda entablar una conversaci\u00f3n con usted...\" o similar).<\/span><\/li>\n<li><span style=\"color: #000000;\">\"Esto parece interesante, pero probablemente para el futuro\" (\"\u00bfPodr\u00edan mantenerme informado de los cambios y actualizaciones a medida que su oferta evoluciona y mis necesidades se consolidan?\" o similar).<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/goconsensus.com\/\" target=\"_blank\" rel=\"noopener\">Consenso<\/a> ofrece a los vendedores una soluci\u00f3n realmente fant\u00e1stica, ya que proporciona una capacidad de demostraci\u00f3n automatizada inteligente que se asigna a los puestos de trabajo y ofrece una lista de temas entre los que elegir, junto con la selecci\u00f3n del nivel de importancia de cada tema.  La \"demo\" resultante se monta a partir de fragmentos de demostraciones preconstruidas, que se corresponden exactamente con lo que el cliente potencial ha solicitado, y todas las elecciones y acciones del cliente potencial se capturan para su uso por parte de los equipos de ventas y marketing del proveedor.<\/span><\/p>\n<p><span style=\"color: #000000;\">Un consultor de navegaci\u00f3n automatizado.  Es tan sencillo como el abecedario: \u00a1encantador!<\/span><\/p>\n<p><span style=\"color: #000000;\">Tenga en cuenta que si un cliente potencial elige todos los temas de una demostraci\u00f3n automatizada de Consensus como \"importantes\", la demostraci\u00f3n agregada resultante tendr\u00e1 probablemente una duraci\u00f3n de entre 10 y 14 minutos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00bfQui\u00e9n debe crear estos activos?  Preventas o \u00e9xito del cliente, no marketing.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00bfPor qu\u00e9?  Porque los equipos de preventa y atenci\u00f3n al cliente conocen mejor los casos de uso t\u00edpicos de los clientes.  Marketing deber\u00eda encargarse de captar las grabaciones, ya sean de preventa o de \u00e9xito del cliente, y alojar estos activos en sitios web y proporcionarlos en forma de plantillas de respuesta de correo electr\u00f3nico, con el seguimiento adecuado para ambos casos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Reconsid\u00e9relo:  \u00a1Invertir unas horas en crear estas minidemos frente a las horas (\u00a1y horas y horas!) que se pierden haciendo demostraciones generales tradicionales a clientes potenciales que \"s\u00f3lo est\u00e1n mirando\"...!<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Low-Touch - Consultores de navegaci\u00f3n en directo<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Para las organizaciones que desean participar de persona a persona por una serie de posibles razones, incluido el deseo de hacer un verdadero Descubrimiento y\/o realmente <em>ayuda<\/em> para conseguir lo que quieren, considere la posibilidad de formar y dedicar recursos espec\u00edficos a estos clientes potenciales que \"s\u00f3lo navegan\".<\/span><\/p>\n<p><span style=\"color: #000000;\">El personal de nivel junior y las nuevas contrataciones destinadas a funciones de preventa o de \u00e9xito del cliente pueden ser perfectas para el puesto de Consultor de navegaci\u00f3n.  (Nota: las grandes organizaciones con programas de formaci\u00f3n de \"academia\" de preventa podr\u00edan utilizar el puesto de consultor de navegaci\u00f3n como el primer puesto de cara al cliente, un trampol\u00edn para las responsabilidades que requieren m\u00e1s experiencia).<\/span><\/p>\n<p><span style=\"color: #000000;\">Los consultores de navegaci\u00f3n en operaciones de poco contacto requerir\u00edan una formaci\u00f3n similar a la que se imparte a los SDR\/BDR y al personal de preventa y \u00e9xito del cliente de nivel subalterno:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Conocimientos b\u00e1sicos de los productos<\/span><\/li>\n<li><span style=\"color: #000000;\">Conocimientos b\u00e1sicos de presentaci\u00f3n de la demostraci\u00f3n de encendido<\/span><\/li>\n<li><span style=\"color: #000000;\">Comprensi\u00f3n razonable de los casos de uso de alta probabilidad para la(s) oferta(s)<\/span><\/li>\n<li><span style=\"color: #000000;\">Conocimientos muy b\u00e1sicos de Discovery<\/span><\/li>\n<li><span style=\"color: #000000;\">Conocimientos b\u00e1sicos y utilizaci\u00f3n de las herramientas adecuadas (por ejemplo, sistema CRM, herramientas de programaci\u00f3n, etc.).<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">En un escenario de poco contacto, los consultores de exploraci\u00f3n se dirigir\u00edan a los clientes potenciales con unas pocas preguntas seguidas de una demostraci\u00f3n de ignici\u00f3n: un resumen breve e intencionado de los problemas que aborda la oferta y las capacidades de alto nivel que proporciona la soluci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los consultores de navegaci\u00f3n de bajo contacto ofrecer\u00edan entonces tres opciones al cliente potencial:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">\"\u00bfLe gustar\u00eda hablar con alguien de ventas?\". (\"\u00bfEs algo que le gustar\u00eda seguir a corto plazo, ahora que ha probado?\")<\/span><\/li>\n<li><span style=\"color: #000000;\">\"\u00bfDesea que le a\u00f1ada a nuestra lista de correo electr\u00f3nico?\" (\"\u00bfDesea recibir actualizaciones peri\u00f3dicas e informaci\u00f3n sobre la oferta y afines?\")<\/span><\/li>\n<li><span style=\"color: #000000;\">\"\u00bfAlgo m\u00e1s?\" (\"\u00bfEs usted algo m\u00e1s que un cliente potencial \"s\u00f3lo de navegaci\u00f3n\"? \u00bfBusca ser socio o revendedor, es analista, medio de comunicaci\u00f3n, etc.? - Puedo ponerle en contacto\").<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Los consultores de navegaci\u00f3n poco t\u00e1ctiles probablemente invertir\u00edan entre 15 y 20 minutos por prospecto.  Utilizando herramientas como <a style=\"color: #000000;\" href=\"https:\/\/www.demoflow.io\/\" target=\"_blank\" rel=\"noopener\">DemoFlow<\/a> o <a style=\"color: #000000;\" href=\"https:\/\/demodesk.com\/\" target=\"_blank\" rel=\"noopener\">DemoDesk<\/a>De este modo, se les proporcionar\u00edan todos los recursos que necesitan en un entorno totalmente habilitado, y sus interacciones se registrar\u00edan autom\u00e1ticamente en el CRM.<\/span><\/p>\n<p><span style=\"color: #000000;\">Reconsid\u00e9relo:  \u00a1Invertir en estos recursos de menor coste frente a las horas que se pierden haciendo demostraciones generales tradicionales a clientes potenciales que \"s\u00f3lo navegan\"...!<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Contacto directo: asesores de navegaci\u00f3n en directo y con experiencia<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">En el caso de organizaciones con ofertas m\u00e1s complejas o ciclos de compra\/venta m\u00e1s largos, puede resultar adecuado un enfoque m\u00e1s directo.  En estos casos, el objetivo es entablar con el cliente potencial conversaciones de descubrimiento m\u00e1s profundas, intercaladas con demostraciones de ignici\u00f3n adecuadas, que aporten m\u00e1s informaci\u00f3n a ambas partes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Se trata de un enfoque m\u00e1s consultivo, que requiere Consultores de Exploraci\u00f3n con m\u00e1s experiencia, un conocimiento m\u00e1s profundo del producto y habilidades de Descubrimiento m\u00e1s agudas.  Entre las ventajas de este enfoque para el vendedor se incluye la obtenci\u00f3n de una informaci\u00f3n de Descubrimiento mucho m\u00e1s rica en una fase temprana del proceso de prospecci\u00f3n, y el enriquecimiento de acuerdo con lo aprendido.  Adem\u00e1s, es probable que los clientes potenciales se decanten por el proveedor que realiza esta inversi\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las organizaciones pueden pasar peri\u00f3dicamente a este puesto (y viceversa) a personal con experiencia en preventa o en atenci\u00f3n al cliente, o bien formarlo y desarrollarlo espec\u00edficamente para esta funci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Evidentemente, las organizaciones podr\u00edan experimentar con uno o m\u00e1s enfoques, incluidas combinaciones de automatizaci\u00f3n sin contacto y equipos de contacto directo e indirecto.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Resumen<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Vemos una oportunidad <em>grande<\/em> oportunidad: reducir los residuos y mejorar la experiencia del cliente aplicando este concepto de Consultor de Navegaci\u00f3n y las Demostraciones de Ignici\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">D\u00edganos lo que piensa.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>La historia de fondo - \u00a1Pru\u00e9belo usted mismo...!<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Aqu\u00ed tienes un ejemplo que puedes probar t\u00fa mismo: \u00a1ver\u00e1s lo que ocurre de primera mano!<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Cualificado Fuera o Dentro<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Supongamos que eres un director de preventa interesado en explorar herramientas de calendario para tu equipo de 25 personas.  Observa que todo el mundo organiza las reuniones con los clientes mediante intercambios de correos electr\u00f3nicos que a menudo van y vienen: es frustrante y sabe que es ineficaz, pero no parece estar afectando negativamente al rendimiento del equipo.<\/span><\/p>\n<p><span style=\"color: #000000;\">Como buen gestor, decide explorar las posibilidades de la automatizaci\u00f3n de calendarios.<\/span><\/p>\n<p><span style=\"color: #000000;\">Te pones en contacto con varios proveedores de software de calendario, revisas sus sitios web, exploras todo lo que puedes en Internet, pero realmente quieres hacerte una idea de lo que es posible con el software.  Para ello, pulsa el bot\u00f3n \"Ver una demostraci\u00f3n\" en la p\u00e1gina web de uno de los proveedores.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00bfY ahora qu\u00e9?<\/span><\/p>\n<p><span style=\"color: #000000;\">Bien, <em>usted<\/em> es ahora el cliente contactado por un BDR\/SDR, que programa una llamada de 15 minutos para \"explorar\".  El objetivo del BDR\/SDR es o bien descartar al cliente (para evitar perder un valioso tiempo de ventas) o bien aceptarlo y concertar una reuni\u00f3n con un vendedor.<\/span><\/p>\n<p><span style=\"color: #000000;\">Comienzas la llamada y el BDR\/SDR pregunta: \"\u00bfse trata de una iniciativa activa?\".<\/span><\/p>\n<p><span style=\"color: #000000;\">R\u00e1pidamente te das cuenta de que si dices \"no\", nunca ver\u00e1s la oferta, estar\u00e1s excluido.  Se le a\u00f1adir\u00e1 a la lista de marketing del vendedor y recibir\u00e1 peri\u00f3dicamente documentos de marketing, actualizaciones y ofertas.  Pero no habr\u00e1 conseguido <em>su<\/em> objetivo, que es hacerse una idea de lo que es posible.  \u00bfQu\u00e9 hay que hacer?<\/span><\/p>\n<p><span style=\"color: #000000;\">Mientes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Usted responde: \"Pues s\u00ed, se trata de una iniciativa activa...\" (francamente, no es una mentira completa, si se estira un poco...) El BDR\/SDR pregunta entonces: \"\u00bfEs usted quien toma las decisiones?\".<\/span><\/p>\n<p><span style=\"color: #000000;\">\"S\u00ed, lo soy\", afirma con orgullo (e inexactitud).<\/span><\/p>\n<p><span style=\"color: #000000;\">\"\u00bfHay presupuesto asignado para este proyecto?\"<\/span><\/p>\n<p><span style=\"color: #000000;\">\"S\u00ed, por supuesto\", respondes, mientras toses en voz baja y algo inc\u00f3moda para ti misma...<\/span><\/p>\n<p><span style=\"color: #000000;\">\"H\u00e1bleme de algunos de sus puntos d\u00e9biles\", le pregunta el BDR\/SDR.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dices: \"Bueno, tenemos muchas ineficiencias con nuestros procesos actuales...\".<\/span><\/p>\n<p><span style=\"color: #000000;\">El BDR\/SDR sugiere: \"Bueno, fijemos una hora para seguir explorando con nuestro vendedor...\", a lo que t\u00fa accedes (porque a\u00fan no has visto nada de su soluci\u00f3n).<\/span><\/p>\n<p><span style=\"color: #000000;\">Y en el lado del vendedor, una campana virtual suena \"Ding Ding Ding\" cuando otro cliente potencial \"cualificado\" entra en el proceso: usted ha sido cualificado como cliente potencial listo para la venta.<\/span><\/p>\n<p><span style=\"color: #000000;\">Hasta ahora, la inversi\u00f3n del proveedor es una llamada de 15 minutos con un BDR\/SDR, y su inversi\u00f3n es similar, pero ha recibido <em>cero<\/em> valor en la interacci\u00f3n.  Pi\u00e9nsalo...<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a1Es una oportunidad!<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Enhorabuena, ha entrado en el \"embudo\" como cliente potencial cualificado.  Tiene su propio registro en el sistema CRM del proveedor y sus respuestas a las preguntas del BDR\/SDR han quedado debidamente registradas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Un d\u00eda antes de su llamada con el vendedor, recibe un recordatorio amistoso de que ma\u00f1ana tiene una reuni\u00f3n para estudiar soluciones.  Tenga en cuenta que este recordatorio se hace en gran parte para<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Aseg\u00farese de no olvidarlo (y de no hacer perder el tiempo al vendedor)<\/span><\/li>\n<li><span style=\"color: #000000;\">Darle la oportunidad de cancelar (para no hacer perder el tiempo al vendedor)<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Ma\u00f1ana llega el momento de la llamada.  Te unes a una sesi\u00f3n de Zoom (o lo que sea) y pasas por un par de cumplidos, despu\u00e9s de lo cual el vendedor <em>repite<\/em> muchas de las preguntas que ya han respondido.  (\u00bfNo leyeron las notas en el sistema CRM?).<\/span><\/p>\n<p><span style=\"color: #000000;\">El vendedor hace algunas preguntas adicionales, que consumen un poco m\u00e1s de tiempo, tras lo cual (con el Descubrimiento considerado \"completo\") el vendedor se lanza a una presentaci\u00f3n general tradicional, y luego cede el papel de \"anfitri\u00f3n\" a un recurso de preventa para que presente una demostraci\u00f3n general.<\/span><\/p>\n<p><span style=\"color: #000000;\">(V\u00e9ase \"<a style=\"color: #000000;\" href=\"https:\/\/greatdemo.com\/es\/asombrosa-awful-web-overview-demostrando-la-anatomia-de-una-web-overview-tradicional-de-1-hora-y-algunas-soluciones\/\">Demostraciones web \"generales\" asombrosamente horribles - La espantosa anatom\u00eda de una demostraci\u00f3n general web tradicional de 1 hora - Y algunas soluciones<\/a>\" y ver c\u00f3mo este triste ejemplo se compara con <em>su<\/em> experiencia...!)<\/span><\/p>\n<p><span style=\"color: #000000;\">Lamentablemente, la mayor parte de lo que se presenta es bla bla bla - podr\u00eda haberse condensado en unos pocos minutos de generaci\u00f3n de visi\u00f3n.  Lo que dura una hora podr\u00eda haberse hecho en 20 minutos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pero espera - \u00bfte has dado cuenta de que la preventa es ahora <em>tambi\u00e9n <\/em>por parte de los vendedores.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00bfImpacto?<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Para ti, no tanto, aparte de que has invertido 1,25 horas por 20 minutos de contenido \u00fatil.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00bfPara el vendedor?  Similar, pero:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Esta oportunidad se mantendr\u00e1 como \"activa\" hasta que, bueno, \u00bfqui\u00e9n sabe?<\/span><\/li>\n<li><span style=\"color: #000000;\">El equipo de ventas (vendedor y personal de preventa) invirti\u00f3 m\u00e1s de una hora en una oportunidad que probablemente no llegar\u00e1 a ninguna parte a corto plazo.<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #000000;\">Eso es despilfarro directo y tambi\u00e9n coste de oportunidad (ya que podr\u00edan haber estado trabajando en una oportunidad que tiene una probabilidad racional de cerrarse).<\/span><\/p>\n<p><span style=\"color: #000000;\">Ahora, piense en su organizaci\u00f3n: \u00bfc\u00f3mo se comparan sus procesos?  Tal vez merezca la pena probar los conceptos de Consultor de navegaci\u00f3n e Ignition Demos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Copyright \u00a9 2020 La Segunda Derivada - Todos los derechos reservados.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Los prospectos que \"s\u00f3lo navegan\" est\u00e1n desatendidos en los enfoques de ventas tradicionales, pero consumen valiosos y costosos recursos de preventa.<\/p>","protected":false},"author":2,"featured_media":26085,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14,20,8,9,12,13,21],"tags":[6,7],"class_list":["post-25295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advanced_topics","category-doing_discovery","category-great-demo-blog","category-growth_development","category-marketing_topics","category-mostly_for_managers","category-vision_generation","tag-articles","tag-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts\/25295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/comments?post=25295"}],"version-history":[{"count":0,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/posts\/25295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/media\/26085"}],"wp:attachment":[{"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/media?parent=25295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/categories?post=25295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greatdemo.com\/es\/wp-json\/wp\/v2\/tags?post=25295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}